{"id":22331,"date":"2011-12-03T00:30:49","date_gmt":"2011-12-02T22:30:49","guid":{"rendered":"http:\/\/blog.dateks.lv\/wp-content\/uploads\/2011\/12\/Zalman-CNPS12X.jpg"},"modified":"2011-12-03T00:30:49","modified_gmt":"2011-12-02T22:30:49","slug":"zalman-cnps12x-2","status":"inherit","type":"attachment","link":"https:\/\/blog.dateks.lv\/ru\/zalman-cnps12x-2\/","title":{"rendered":"Zalman CNPS12X"},"author":7,"featured_media":0,"comment_status":"open","ping_status":"open","template":"","meta":[],"class_list":["post-22331","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/blog.dateks.lv\/wp-content\/uploads\/2011\/12\/Zalman-CNPS12X.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"282\" src=\"https:\/\/blog.dateks.lv\/wp-content\/uploads\/2011\/12\/Zalman-CNPS12X-300x282.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/blog.dateks.lv\/wp-content\/uploads\/2011\/12\/Zalman-CNPS12X-300x282.jpg 300w, https:\/\/blog.dateks.lv\/wp-content\/uploads\/2011\/12\/Zalman-CNPS12X.jpg 817w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p class=\"attachment\"><a href='https:\/\/blog.dateks.lv\/wp-content\/uploads\/2011\/12\/Zalman-CNPS12X.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"282\" src=\"https:\/\/blog.dateks.lv\/wp-content\/uploads\/2011\/12\/Zalman-CNPS12X-300x282.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/blog.dateks.lv\/wp-content\/uploads\/2011\/12\/Zalman-CNPS12X-300x282.jpg 300w, https:\/\/blog.dateks.lv\/wp-content\/uploads\/2011\/12\/Zalman-CNPS12X.jpg 817w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":"817","height":"768","hwstring_small":"height='96' width='102'","file":"2011\/12\/Zalman-CNPS12X.jpg","sizes":{"thumbnail":{"file":"Zalman-CNPS12X-150x150.jpg","width":"150","height":"150","source_url":"https:\/\/blog.dateks.lv\/wp-content\/uploads\/2011\/12\/Zalman-CNPS12X-150x150.jpg"},"medium":{"file":"Zalman-CNPS12X-300x282.jpg","width":"300","height":"282","source_url":"https:\/\/blog.dateks.lv\/wp-content\/uploads\/2011\/12\/Zalman-CNPS12X-300x282.jpg"},"full":{"file":"Zalman-CNPS12X.jpg","width":817,"height":768,"mime_type":"image\/jpeg","source_url":"https:\/\/blog.dateks.lv\/wp-content\/uploads\/2011\/12\/Zalman-CNPS12X.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":""}},"post":null,"source_url":"https:\/\/blog.dateks.lv\/wp-content\/uploads\/2011\/12\/Zalman-CNPS12X.jpg","filename":"Zalman-CNPS12X.jpg","filesize":166237,"_links":{"self":[{"href":"https:\/\/blog.dateks.lv\/ru\/wp-json\/wp\/v2\/media\/22331","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.dateks.lv\/ru\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/blog.dateks.lv\/ru\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/blog.dateks.lv\/ru\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.dateks.lv\/ru\/wp-json\/wp\/v2\/comments?post=22331"}]}}